{"id":6624,"date":"2026-02-03T10:45:19","date_gmt":"2026-02-03T13:45:19","guid":{"rendered":"https:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/?page_id=6624"},"modified":"2026-07-08T09:40:00","modified_gmt":"2026-07-08T12:40:00","slug":"parque-general-san-martin","status":"publish","type":"page","link":"https:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/biodiversidad-y-ecoparque\/parque-general-san-martin\/","title":{"rendered":"Parque General San Mart\u00edn"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; background_color=\u00bbRGBA(255,255,255,0)\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb169deg\u00bb background_color_gradient_stops=\u00bb#ffffff 15%|#0a0000 100%\u00bb background_image=\u00bbhttps:\/\/mza-dicaws-portal-uploads-media-prod.s3.us-east-1.amazonaws.com\/informacion-oficial\/uploads\/sites\/12\/2025\/05\/FMS_5958-scaled.jpg\u00bb background_blend=\u00bbscreen\u00bb min_height=\u00bb1135px\u00bb custom_margin=\u00bb3px|||||\u00bb custom_padding=\u00bb3px||21px|||\u00bb border_color_all=\u00bb#FFFFFF\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb max_width=\u00bb2560px\u00bb custom_padding=\u00bb39px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbPARQUE GENERAL SAN MART\u00cdN\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|300|||||||\u00bb title_text_align=\u00bbcenter\u00bb title_text_color=\u00bbgcid-heading-color\u00bb title_font_size=\u00bb3.5rem\u00bb min_height=\u00bb54px\u00bb custom_margin=\u00bb||-1px|||\u00bb title_text_shadow_style=\u00bbpreset1&#8243; global_colors_info=\u00bb{%22gcid-heading-color%22:%91%22title_text_color%22%93}\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb2560px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(255,255,255,0.65)\u00bb custom_padding=\u00bb11px|0px|20px|25px|false|false\u00bb border_radii=\u00bbon|8px|8px|8px|8px\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p>En 1896, cuando Mendoza a\u00fan buscaba ensanchar su pecho, alguien imagin\u00f3 lo imposible: que el desierto fuera bosque. As\u00ed naci\u00f3 el Parque del Oeste, para transformar el rigor de la aridez en aire h\u00famedo, fresco y puro.<\/p>\n<p>De generaci\u00f3n en generaci\u00f3n, este parque, luego llamado General San Mart\u00edn, cambi\u00f3: traz\u00f3 caminos, llen\u00f3 de vida las fuentes y el lago; acogi\u00f3 instituciones; se visti\u00f3 de arte, llen\u00f3 de aplausos estadios y escenarios. De oasis planificado pas\u00f3 a postal de identidad; de jard\u00edn aristocr\u00e1tico a \u00edcono popular, llegando a ser declarado \u00c1rea Ambiental Urbana Protegida, para que su esp\u00edritu perdurara.<\/p>\n<p>El Parque General San Mart\u00edn es nuestra joya ambiental. Mientras lo preservemos, este nos ofrecer\u00e1 una verdad definitiva: siempre tendremos un refugio emocional donde volver a encontrarnos con la esencia de lo que somos.<\/p>\n<p>[\/et_pb_text][et_pb_video_slider _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_video_slider_item src=\u00bbhttps:\/\/youtu.be\/__TyJN9vtQU?si=-nYD2_TSaYVKprRl\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb show_image_overlay=\u00bboff\u00bb][\/et_pb_video_slider_item][\/et_pb_video_slider][et_pb_image src=\u00bbhttps:\/\/mza-dicaws-portal-uploads-media-prod.s3.amazonaws.com\/informacion-oficial\/uploads\/sites\/12\/2026\/02\/BANNERS_WEB_parque-scaled.png\u00bb title_text=\u00bbBANNERS_WEB_parque\u00bb url=\u00bbhttps:\/\/mza-dicaws-portal-uploads-media-prod.s3.amazonaws.com\/informacion-oficial\/uploads\/sites\/12\/2026\/02\/PGSM-Presentacion-2026.pdf\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb2560px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/mza-dicaws-portal-uploads-media-prod.s3.amazonaws.com\/informacion-oficial\/uploads\/sites\/12\/2026\/02\/BANNER_WEB_parque_02-scaled.png\u00bb title_text=\u00bbBANNER_WEB_parque_02&#8243; url=\u00bbhttps:\/\/mza-dicaws-portal-uploads-media-prod.s3.amazonaws.com\/informacion-oficial\/uploads\/sites\/12\/2026\/02\/DECRETO-No-2002-2025-1.pdf\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_3,1_3,1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(255,255,255,0.37)\u00bb max_width=\u00bb2560px\u00bb min_height=\u00bb409.1px\u00bb border_radii=\u00bbon|8px|8px|8px|8px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbEl Parque\u00bb url=\u00bb#parque\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf557;||fa||900&#8243; icon_color=\u00bb#0C71C3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bbgcid-9107e7ce-36aa-491e-a581-b7de38ef6b97&#8243; body_text_color=\u00bbgcid-840cd285-ee6f-49c1-abc9-5e893f3235b8&#8243; custom_margin=\u00bb||10%||false|false\u00bb link_option_url=\u00bb#parque\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22body_text_color%22,%22body_text_color%22%93,%22gcid-9107e7ce-36aa-491e-a581-b7de38ef6b97%22:%91%22header_text_color%22%93}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbConsultas y denuncias\u00bb url=\u00bb#\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xe066;||divi||400&#8243; icon_color=\u00bb#0C71C3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bbgcid-9107e7ce-36aa-491e-a581-b7de38ef6b97&#8243; body_text_color=\u00bbgcid-840cd285-ee6f-49c1-abc9-5e893f3235b8&#8243; custom_margin=\u00bb||-0.3%||false|false\u00bb link_option_url=\u00bb#\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22body_text_color%22,%22body_text_color%22%93,%22gcid-9107e7ce-36aa-491e-a581-b7de38ef6b97%22:%91%22header_text_color%22%93}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbEcoparque\u00bb url=\u00bb#ecoparque\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf4ba;||fa||900&#8243; icon_color=\u00bb#0C71C3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bbgcid-9107e7ce-36aa-491e-a581-b7de38ef6b97&#8243; body_text_color=\u00bbgcid-840cd285-ee6f-49c1-abc9-5e893f3235b8&#8243; custom_margin=\u00bb||10%||false|false\u00bb link_option_url=\u00bb#ecoparque\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22body_text_color%22,%22body_text_color%22%93,%22gcid-9107e7ce-36aa-491e-a581-b7de38ef6b97%22:%91%22header_text_color%22%93}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbTraslado animales de corral\u00bb url=\u00bb#corral\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf5b6;||fa||900&#8243; icon_color=\u00bb#0C71C3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bbgcid-9107e7ce-36aa-491e-a581-b7de38ef6b97&#8243; body_text_color=\u00bbgcid-840cd285-ee6f-49c1-abc9-5e893f3235b8&#8243; custom_margin=\u00bb||10%||false|false\u00bb link_option_url=\u00bb#corral\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22body_text_color%22,%22body_text_color%22%93,%22gcid-9107e7ce-36aa-491e-a581-b7de38ef6b97%22:%91%22header_text_color%22%93}\u00bb][\/et_pb_blurb][\/et_pb_column][et_pb_column type=\u00bb1_3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb title=\u00bbBienestar Animal\u00bb url=\u00bb#bienestar\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf6f0;||fa||900&#8243; icon_color=\u00bb#0C71C3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bbgcid-9107e7ce-36aa-491e-a581-b7de38ef6b97&#8243; body_text_color=\u00bbgcid-840cd285-ee6f-49c1-abc9-5e893f3235b8&#8243; custom_margin=\u00bb||10%||false|false\u00bb link_option_url=\u00bb#bienestar\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22body_text_color%22,%22body_text_color%22%93,%22gcid-9107e7ce-36aa-491e-a581-b7de38ef6b97%22:%91%22header_text_color%22%93}\u00bb][\/et_pb_blurb][et_pb_blurb title=\u00bbTraslados animales ex\u00f3ticos\u00bb url=\u00bb#exoticos\u00bb use_icon=\u00bbon\u00bb font_icon=\u00bb&#xf5b0;||fa||900&#8243; icon_color=\u00bb#0C71C3&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbcenter\u00bb header_text_color=\u00bbgcid-9107e7ce-36aa-491e-a581-b7de38ef6b97&#8243; body_text_color=\u00bbgcid-840cd285-ee6f-49c1-abc9-5e893f3235b8&#8243; custom_margin=\u00bb||10%||false|false\u00bb link_option_url=\u00bb#exoticos\u00bb locked=\u00bboff\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22body_text_color%22,%22body_text_color%22%93,%22gcid-9107e7ce-36aa-491e-a581-b7de38ef6b97%22:%91%22header_text_color%22%93}\u00bb][\/et_pb_blurb][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; background_color=\u00bbRGBA(255,255,255,0)\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb169deg\u00bb background_color_gradient_stops=\u00bb#ffffff 15%|#0a0000 100%\u00bb background_image=\u00bbhttps:\/\/mza-dicaws-portal-uploads-media-prod.s3.us-east-1.amazonaws.com\/informacion-oficial\/uploads\/sites\/12\/2025\/05\/FMS_5958-scaled.jpg\u00bb background_blend=\u00bbscreen\u00bb min_height=\u00bb1135px\u00bb custom_margin=\u00bb3px|||||\u00bb custom_padding=\u00bb3px||21px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row module_id=\u00bbparque\u00bb _builder_version=\u00bb4.27.4&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb max_width=\u00bb2560px\u00bb min_height=\u00bb117px\u00bb custom_margin=\u00bb61px|auto|-3px|auto||\u00bb custom_padding=\u00bb5px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbEL PARQUE\u00bb admin_label=\u00bbFlora Nativa\u00bb module_id=\u00bbareas-naturales\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bb|300|||||||\u00bb title_text_align=\u00bbleft\u00bb title_text_color=\u00bbgcid-body-color\u00bb title_font_size=\u00bb40px\u00bb min_height=\u00bb39px\u00bb custom_margin=\u00bb||-1px|||\u00bb global_colors_info=\u00bb{%22gcid-body-color%22:%91%22title_text_color%22%93}\u00bb][\/et_pb_heading][et_pb_heading title=\u00bbGENERAL SAN MART\u00cdN\u00bb admin_label=\u00bbFlora Nativa\u00bb module_id=\u00bbareas-naturales\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bb|300|||||||\u00bb title_text_align=\u00bbleft\u00bb title_text_color=\u00bbgcid-body-color\u00bb title_font_size=\u00bb40px\u00bb min_height=\u00bb39px\u00bb custom_margin=\u00bb||40px|||\u00bb global_colors_info=\u00bb{%22gcid-body-color%22:%91%22title_text_color%22%93}\u00bb][\/et_pb_heading][et_pb_blurb image=\u00bbhttps:\/\/mza-dicaws-portal-uploads-media-prod.s3.us-east-1.amazonaws.com\/informacion-oficial\/uploads\/sites\/12\/2025\/04\/Logo-parque-color.jpeg\u00bb icon_placement=\u00bbleft\u00bb content_max_width=\u00bb1100px\u00bb icon_placement_tablet=\u00bbleft\u00bb icon_placement_phone=\u00bbtop\u00bb icon_placement_last_edited=\u00bbon|phone\u00bb image_icon_width_tablet=\u00bb\u00bb image_icon_width_phone=\u00bb155px\u00bb image_icon_width_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bb|300|||||||\u00bb header_text_color=\u00bbgcid-840cd285-ee6f-49c1-abc9-5e893f3235b8&#8243; image_icon_custom_margin=\u00bb||||false|false\u00bb text_orientation=\u00bbjustified\u00bb width=\u00bb100%\u00bb max_width=\u00bb100%\u00bb custom_margin=\u00bb||45px||false|false\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb border_width_top_image=\u00bb40px\u00bb border_width_right_image=\u00bb40px\u00bb border_color_right_image=\u00bbRGBA(255,255,255,0)\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22header_text_color%22%93}\u00bb]<\/p>\n<p><strong>El Parque Hist\u00f3rico General San Mart\u00edn<\/strong><span>\u00a0es el \u00a0parque m\u00e1s antiguo de la Provincia de Mendoza.\u00a0 Se encuentra ubicado en la Ciudad de Mendoza delimitado por las avenidas Carlos Washington Lencinas (al Norte), San Francisco De As\u00eds (al Sur) y Boulogne Sur Mer (al Este). En tanto que la precordillera mendocina es el l\u00edmite Oeste. El l\u00edmite Sur se ha modificado por las ampliaciones realizadas al Parque (extendi\u00e9ndose m\u00e1s al sur), siendo hoy el l\u00edmite el Zanj\u00f3n Fr\u00edas, divisorio de la Ciudad de Mendoza y el Departamento de Godoy Cruz, municipios de la Provincia de Mendoza. El parque abarca 307 ha cultivadas y 86 ha en expansi\u00f3n con 17 km de recorrido.<\/span><\/p>\n<p>[\/et_pb_blurb][et_pb_slider _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_font_size=\u00bb1.5rem\u00bb body_text_align=\u00bbleft\u00bb background_color=\u00bbrgba(10,10,10,0.3)\u00bb button_alignment=\u00bbcenter\u00bb max_width=\u00bb800px\u00bb module_alignment=\u00bbcenter\u00bb min_height=\u00bb559.2px\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb29px||62px||false|false\u00bb border_radii=\u00bbon|8px|8px|8px|8px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_slide heading=\u00bbObjetivos\u00bb button_text=\u00bbLey 8.945&#8243; button_link=\u00bbhttps:\/\/www.mendoza.gov.ar\/ecoparque\/wp-content\/uploads\/sites\/35\/2017\/09\/Ley-8945-Creaci%C3%B3n-DEM-y-DPP.pdf\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Lograr una correcta gesti\u00f3n, administraci\u00f3n y planificaci\u00f3n ambiental del Parque.<\/li>\n<li>Promover la protecci\u00f3n de la flora y fauna aut\u00f3ctonas de Mendoza y Regi\u00f3n Cuyo a trav\u00e9s de programas de\u00a0<span>Conservaci\u00f3n e investigaci\u00f3n sobre las especies aut\u00f3ctonas de Mendoza y Regi\u00f3n Cuyo.<\/span><\/li>\n<li><span>Promover la educaci\u00f3n a los visitantes del lugar sobre el cuidado de la biodiversidad aut\u00f3ctona de Mendoza y Regi\u00f3n Cuyo.<\/span><\/li>\n<li><span>Resguardar el patrimonio cultural existente en el predio.<\/span><\/li>\n<li><span>Utilizar los senderos del predio para mostrar las herramientas y tecnolog\u00edas disponibles para el cuidado del ambiente y la preservaci\u00f3n de los h\u00e1bitats naturales de Mendoza.<\/span><\/li>\n<li><span>Promover la participaci\u00f3n de los pueblos originarios en la educaci\u00f3n hacia una cosmovisi\u00f3n de integraci\u00f3n arm\u00f3nica con la naturaleza.<\/span><\/li>\n<\/ul>\n<ul><\/ul>\n<p>[\/et_pb_slide][et_pb_slide heading=\u00bbPrincipios Generales\u00bb button_text=\u00bbDecreto 451&#8243; button_link=\u00bbhttps:\/\/www.mendoza.gov.ar\/ecoparque\/wp-content\/uploads\/sites\/35\/2018\/03\/Decreto-reglamentario-451.pdf\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<ul><\/ul>\n<ul><\/ul>\n<ul>\n<li>La generaci\u00f3n de consciencia p\u00fablica a trav\u00e9s de la educaci\u00f3n en la conservaci\u00f3n de la biodiversidad aut\u00f3ctona de Mendoza y la Regi\u00f3n Cuyo y el desarrollo sustentable.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>La promoci\u00f3n de actividades de investigaci\u00f3n cient\u00edfica en beneficio de la conservaci\u00f3n de la fauna y flora aut\u00f3ctonas de Mendoza y la Regi\u00f3n Cuyo.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li>La generaci\u00f3n de un espacio f\u00edsico natural para la recreaci\u00f3n y el esparcimiento de la sociedad.<\/li>\n<\/ul>\n<p>[\/et_pb_slide][et_pb_slide heading=\u00bbHistoria\u00bb button_text=\u00bbLeer m\u00e1s\u00bb button_link=\u00bbhttps:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/biodiversidad-y-ecoparque\/#\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_text_align=\u00bbcenter\u00bb body_text_align=\u00bbjustify\u00bb text_orientation=\u00bbjustified\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p><span>La base te\u00f3rica para la creaci\u00f3n del Parque del Oeste, como se lo denomin\u00f3 inicialmente, se fund\u00f3 en los estudios realizados por el m\u00e9dico higienista Emilio Coni. Su an\u00e1lisis acerca del estado sanitario de Mendoza conclu\u00eda con una serie de acciones que deb\u00edan encararse para mejorar la salubridad p\u00fablica. Estas eran por ejemplo, construir un hospital\u00a0 provincial en una zona elevada de la ciudad, protegido por barreras verdes. Para concretarlo, deb\u00edan hacerse obras de infraestructura como canales de riego y defensas aluvionales. Con este fin, las autoridades provinciales, encabezadas por el gobernador Francisco Moyano y el ministro de Hacienda, Emilio Civit, sancionaron el 6 de noviembre de 1896 la Ley 19, autorizando a erogar la suma de 158.000 pesos para realizar las tareas previstas en tierras fiscales situadas al oeste de la Ciudad Nueva. Cinco d\u00edas despu\u00e9s Carlos Thays, director de paseos p\u00fablicos de Buenos Aires, present\u00f3 los planos preliminares en donde destinaba 329 hect\u00e1reas para la instalaci\u00f3n del parque y dejaba en reserva 70 hect\u00e1reas para quintas.<\/span><\/p>\n<ul><\/ul>\n<p>[\/et_pb_slide][\/et_pb_slider][et_pb_heading title=\u00bbGaler\u00eda\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|300|||||||\u00bb title_text_color=\u00bbgcid-9d8d6552-a4b0-4171-847a-f5c0d7177503&#8243; title_font_size=\u00bb1.5rem\u00bb background_color=\u00bbRGBA(255,255,255,0.65)\u00bb min_height=\u00bb49px\u00bb custom_margin=\u00bb||-2px|||\u00bb custom_padding=\u00bb11px||3px|30px||\u00bb border_radii=\u00bbon|8px|8px|8px|8px\u00bb global_colors_info=\u00bb{%22gcid-9d8d6552-a4b0-4171-847a-f5c0d7177503%22:%91%22title_text_color%22%93}\u00bb][\/et_pb_heading][et_pb_gallery gallery_ids=\u00bb579,600,598,595,599,597,587,588,589,590,591,592,593,594&#8243; show_title_and_caption=\u00bboff\u00bb show_pagination=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb29px||-5px|||\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][et_pb_gallery gallery_ids=\u00bb580,581,582,583,584,589,585,586&#8243; show_title_and_caption=\u00bboff\u00bb show_pagination=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.27.4&#8243; background_color=\u00bbRGBA(255,255,255,0)\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb169deg\u00bb background_color_gradient_stops=\u00bb#ffffff 15%|#0a0000 100%\u00bb background_image=\u00bbhttps:\/\/mza-dicaws-portal-uploads-media-prod.s3.us-east-1.amazonaws.com\/informacion-oficial\/uploads\/sites\/12\/2025\/05\/ECO-acceso-1.jpg\u00bb background_blend=\u00bbscreen\u00bb min_height=\u00bb1135px\u00bb custom_margin=\u00bb3px|||||\u00bb custom_padding=\u00bb3px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row module_id=\u00bbecoparque\u00bb _builder_version=\u00bb4.27.4&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb max_width=\u00bb2560px\u00bb min_height=\u00bb117px\u00bb custom_margin=\u00bb60px|auto|-3px|auto||\u00bb custom_padding=\u00bb5px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbECOPARQUE\u00bb admin_label=\u00bbFlora Nativa\u00bb module_id=\u00bbareas-naturales\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bb|300|||||||\u00bb title_text_align=\u00bbleft\u00bb title_text_color=\u00bbgcid-body-color\u00bb title_font_size=\u00bb40px\u00bb min_height=\u00bb39px\u00bb custom_margin=\u00bb||-1px|||\u00bb global_colors_info=\u00bb{%22gcid-body-color%22:%91%22title_text_color%22%93}\u00bb][\/et_pb_heading][et_pb_heading title=\u00bbMENDOZA\u00bb admin_label=\u00bbFlora Nativa\u00bb module_id=\u00bbareas-naturales\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh2&#8243; title_font=\u00bb|300|||||||\u00bb title_text_align=\u00bbleft\u00bb title_text_color=\u00bbgcid-body-color\u00bb title_font_size=\u00bb40px\u00bb min_height=\u00bb39px\u00bb custom_margin=\u00bb||-1px|||\u00bb global_colors_info=\u00bb{%22gcid-body-color%22:%91%22title_text_color%22%93}\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb max_width=\u00bb2560px\u00bb min_height=\u00bb282.7px\u00bb custom_margin=\u00bb|auto|-3px|auto||\u00bb custom_padding=\u00bb5px|0px|4px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_blurb image=\u00bbhttps:\/\/mza-dicaws-portal-uploads-media-prod.s3.us-east-1.amazonaws.com\/informacion-oficial\/uploads\/sites\/12\/2025\/04\/LOGO-ECOPARQUE.jpeg\u00bb icon_placement=\u00bbleft\u00bb image_icon_width=\u00bb200px\u00bb content_max_width=\u00bb1100px\u00bb icon_placement_tablet=\u00bbleft\u00bb icon_placement_phone=\u00bbtop\u00bb icon_placement_last_edited=\u00bbon|phone\u00bb image_icon_width_tablet=\u00bb200px\u00bb image_icon_width_phone=\u00bb200px\u00bb image_icon_width_last_edited=\u00bbon|phone\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_font=\u00bb|300|||||||\u00bb header_text_color=\u00bbgcid-840cd285-ee6f-49c1-abc9-5e893f3235b8&#8243; image_icon_custom_margin=\u00bb-60px|||44px|false|false\u00bb text_orientation=\u00bbjustified\u00bb width=\u00bb100%\u00bb max_width=\u00bb100%\u00bb custom_margin=\u00bb||43px|||\u00bb custom_padding=\u00bb46px|||||\u00bb border_color_all_image=\u00bbRGBA(255,255,255,0)\u00bb border_width_top_image=\u00bb40px\u00bb border_width_right_image=\u00bb40px\u00bb border_color_right_image=\u00bbRGBA(255,255,255,0)\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22header_text_color%22%93}\u00bb]<\/p>\n<p><span>El Ecoparque Mendoza, es la instituci\u00f3n que reemplaza al ex-zool\u00f3gico de la Provincia de Mendoza. Es la\u00a0<\/span><a href=\"http:\/\/www.saij.gob.ar\/8945-local-mendoza-crean-direccion-ecoparque-mendoza-direccion-parques-paseos-publicos-lpm0008945-2016-12-27\/123456789-0abc-defg-549-8000mvorpyel\">Ley Provincial 8945<\/a><span>,\u00a0 sancionada en diciembre de 2016, la que define a esta nueva instituci\u00f3n como \u201cun parque que a trav\u00e9s de espacios naturales, programas educativos, actividades de conservaci\u00f3n, recepci\u00f3n, rehabilitaci\u00f3n y derivaci\u00f3n de especies nativas e infraestructura acorde, busca alcanzar la concientizaci\u00f3n ecol\u00f3gica por medio de la sensibilizaci\u00f3n, la motivaci\u00f3n y el conocimiento de la problem\u00e1tica que enfrenta el ambiente natural que nos rodea. <\/span><\/p>\n<p><span>En este lugar, los visitantes pueden aprender sobre las interrelaciones entre los organismos y su ambiente, a partir de principios de respeto por todas las formas de vida, su importancia en el ambiente, y la preservaci\u00f3n y conservaci\u00f3n de los ecosistemas, adem\u00e1s de recibir herramientas para inspirar la b\u00fasqueda de soluciones a la problem\u00e1tica ambiental.\u201d<\/span><\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb2560px\u00bb custom_padding=\u00bb0px||4px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_tabs active_tab_background_color=\u00bb#FFFFFF\u00bb active_tab_text_color=\u00bb#333333&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb tab_text_color=\u00bb#9e9e9e\u00bb body_text_align=\u00bbleft\u00bb body_text_color=\u00bb#333333&#8243; body_font_size=\u00bb0.9rem\u00bb tab_font=\u00bb|600|||||||\u00bb tab_font_size=\u00bb1rem\u00bb background_color=\u00bbrgba(255,255,255,0.65)\u00bb custom_margin=\u00bb35px|||||\u00bb border_radii=\u00bbon|8px|8px|8px|8px\u00bb global_colors_info=\u00bb{%22gcid-9d8d6552-a4b0-4171-847a-f5c0d7177503%22:%91%22tab_text_color%22%93,%22gcid-53054839-b83d-4ef0-8659-8a010e6148fd%22:%91%22body_text_color%22,%22active_tab_text_color%22%93}\u00bb][et_pb_tab title=\u00bbInstitucional\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_enable_image=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>Institucional<\/strong><strong><\/strong><\/p>\n<figure><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mza-dicaws-portal-uploads-media-prod.s3.us-east-1.amazonaws.com\/informacion-oficial\/uploads\/sites\/12\/2025\/04\/Audit-300x169.png\" width=\"298\" height=\"168\" alt=\"\" class=\"wp-image-505 alignnone size-medium\" \/><\/figure>\n<div>\n<p class=\"normal\"><span lang=\"ES\">El Ecoparque Mendoza, es la instituci\u00f3n que reemplaza al ex-zool\u00f3gico de la Provincia de Mendoza. Es la<span>\u00a0<\/span><a href=\"http:\/\/www.saij.gob.ar\/8945-local-mendoza-crean-direccion-ecoparque-mendoza-direccion-parques-paseos-publicos-lpm0008945-2016-12-27\/123456789-0abc-defg-549-8000mvorpyel\"><span style=\"color: #0091f2\">Ley Provincial 8945<\/span><\/a>,\u00a0 sancionada en diciembre de 2016, la que define a esta nueva instituci\u00f3n como \u201cun parque que a trav\u00e9s de espacios naturales, programas educativos, actividades de conservaci\u00f3n, recepci\u00f3n, rehabilitaci\u00f3n y derivaci\u00f3n de especies nativas e infraestructura acorde, busca alcanzar la concientizaci\u00f3n ecol\u00f3gica por medio de la sensibilizaci\u00f3n, la motivaci\u00f3n y el conocimiento de la problem\u00e1tica que enfrenta el ambiente natural que nos rodea. En este lugar, los visitantes pueden aprender sobre las interrelaciones entre los organismos y su ambiente, a partir de principios de respeto por todas las formas de vida, su importancia en el ambiente y la preservaci\u00f3n y conservaci\u00f3n de los ecosistemas, adem\u00e1s de recibir herramientas para inspirar la b\u00fasqueda de soluciones a la problem\u00e1tica ambiental.\u201d <a>Seguir leyendo&#8230;<\/a><\/span><\/p>\n<\/div>\n<p>[\/et_pb_tab][et_pb_tab title=\u00bbAntecedentes hist\u00f3ricos y patrimoniales\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>Antecedentes hist\u00f3ricos y patrimoniales<\/strong><\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mza-dicaws-portal-uploads-media-prod.s3.us-east-1.amazonaws.com\/informacion-oficial\/uploads\/sites\/12\/2025\/04\/Pinar-achivos-e1633014585113-700x264-1-300x113.jpg\" width=\"381\" height=\"143\" alt=\"\" class=\"wp-image-510 alignnone size-medium\" \/><\/strong><\/p>\n<p>El ex-zool\u00f3gico de Mendoza, como instituci\u00f3n, fue creado en 1903, durante la gesti\u00f3n del Gobernador Jos\u00e9 Galigniana Segura. Formaba parte del Plan General que hab\u00eda realizado el paisajista franc\u00e9s Carlos Thays para el Parque del Oeste, en el a\u00f1o 1896. El zool\u00f3gico se ubicaba originalmente sobre la avenida de circunvalaci\u00f3n oeste, al frente de donde hoy se encuentra el Hogar Eva Per\u00f3n (1953).<\/p>\n<p>Seg\u00fan Ana Castro (1996)<a><sup>[1]<\/sup><\/a>, en el Censo Municipal de 1903 figuran las noticias m\u00e1s antiguas del mismo. Reci\u00e9n a partir de abril de 1904 comienza a figurar el Guardi\u00e1n del Jard\u00edn Zool\u00f3gico, con un jornal de $1,50.- Una noticia procedente de Buenos Aires y publicada en Los Andes el d\u00eda 7 de abril da cuenta del ingreso de un guanaco y un avestruz; agrega que el lugar se ir\u00e1 poblando a medida que lleguen los ejemplares prometidos. En ese mismo mes se realizan diferentes trabajos en el sector: tendido del alambrado alrededor del lago destinado a los patos, gansos y aves acu\u00e1ticas; construcci\u00f3n de cuatro jaulas con cimientos de piedra y pilastras de material cocido y una quinta fabricada con madera y alambre; colocaci\u00f3n de la baranda para la jaula del c\u00f3ndor; ubicaci\u00f3n de ocho bancos para los visitantes: trazado de quinientos metros para las acequias empedradas, construcci\u00f3n de veredas y paseos y plantaci\u00f3n de yucas, fresnos y plantas de jard\u00edn. Posiblemente en ese a\u00f1o se haya inaugurado el Zoo.<\/p>\n<p>Hacia 1905, se elabora el proyecto del pabell\u00f3n de los leones. Quince obreros construyen jaulas, veredas, acequias y excavan hoyos para plantas. Un a\u00f1o despu\u00e9s se instala un galp\u00f3n dep\u00f3sito, se concluye el puente r\u00fastico y se trabaja en el pabell\u00f3n de los leones que queda finalizado en febrero de 1907. Aumenta el n\u00famero de habitantes con la incorporaci\u00f3n de avestruces, aguiluchos, chimangos, teros, lechuza, pitojuanes y becasina adquirido al jefe pol\u00edtico de Lavalle. Entran tambi\u00e9n gaviotas de mar y tordos de procedencia chilena.<\/p>\n<p>En el\u00a0<em>\u00c1lbum Argentino <\/em>de 1907, se describe al zool\u00f3gico con una extensi\u00f3n de seis hect\u00e1reas en la que los pabellones y boxes de los animales se alternan con jardines y lagos.<\/p>\n<p>En 1910 se inaugura el trencito del parque que recorr\u00eda 7 km hasta la entrada del antiguo zoo. Hacia la d\u00e9cada de 1940 se traslada a la ubicaci\u00f3n actual.<\/p>\n<p>En 1913 el Cerro del Pilar cambia el nombre por Cerro de la Gloria, all\u00ed se emplazar\u00eda el monumento al Ej\u00e9rcito de Los Andes (autor: Juan Manuel Ferrari, construido entre 1909 y 1914).<\/p>\n<p>En 1933 se inician las obras del Parque Aborigen, dirigidas por Benito de San Mart\u00edn, en un predio de 9 hect\u00e1reas, hacia el NO del Parque. La idea principal de ese proyecto era reunir all\u00ed la mayor cantidad de flora aut\u00f3ctona e incluir una secci\u00f3n de cactus. El sector se puebla con ejemplares de jarilla, chilca, molle, piquill\u00edn, cha\u00f1ar, alpataco, algarrobo, retamillo, garabato y aguaribay. Una parte se ocupa con cactus tra\u00eddos de la precordillera, principalmente de la Quebrada del Toro. Al a\u00f1o siguiente se instala la escultura de Luis Perlotti \u201cSaludo al Sol\u201d.<\/p>\n<p>En 1937 se asfaltan las calles del Parque y se inauguran Playas Serranas.<\/p>\n<p>En 1939 se inician una serie de emprendimientos muy importantes que tiene como inspirador y ejecutor al Director de Parques, Calles y Paseos, Arq. Daniel Ramos Correas; quien se desempe\u00f1\u00f3 en este cargo entre 1938 y 1943. Desarroll\u00f3 el Plan de Conservaci\u00f3n, Terminaci\u00f3n y Mejoramiento del Parque General San Mart\u00edn<a><sup>[2]<\/sup><\/a>. Empieza a extenderse hacia el Oeste. La ladera Este del Cerro de la Gloria sirve de asentamiento para el nuevo Parque Zool\u00f3gico<a><sup>[3]<\/sup><\/a>, en un predio de casi 40 hect\u00e1reas. Se modifica el entorno del Monumento al Ej\u00e9rcito de los Andes; y del lado Sur del Cerro se construye en Teatro Griego.<\/p>\n<p>El antiguo zool\u00f3gico se convierte en bosque rodeando al Teatro Pulgarcito. Y donde estuvieron los leones se construye una confiter\u00eda<a><sup>[4]<\/sup><\/a>.<\/p>\n<p>El gobernador en 1940 anuncia en la Legislatura los trabajos realizados en el nuevo zool\u00f3gico: demarcaci\u00f3n y cierre de los terrenos; trazado y construcci\u00f3n de las obras b\u00e1sicas de los caminos; ampliaci\u00f3n del riego mediante la construcci\u00f3n de dos tanques de 250.000 litros; plantaci\u00f3n de m\u00e1s de 1.000 \u00e1rboles y excavaci\u00f3n de un lago para aves acu\u00e1ticas. Para esa fecha el Zool\u00f3gico cuenta con m\u00e1s de 1.400 ejemplares.<\/p>\n<p>Para junio de 1941 el organismo ya hab\u00eda sido trasladado. Se han obtenido animales por canje con los zool\u00f3gicos de Buenos Aires y Montevideo. El de Mendoza exhibe en esa \u00e9poca 195 mam\u00edferos y 1.271 aves. Un a\u00f1o m\u00e1s tarde llega a 282 y 1.503 respectivamente.<\/p>\n<p>El Mensaje de 1942 enumera las obras de infraestructura realizadas: sanitarios para el p\u00fablico; terminaci\u00f3n de entrada y vereda; ampliaci\u00f3n de la playa de estacionamiento de 1.800m<sup>2<\/sup>; construcci\u00f3n de una pileta desarenadora de 330 m<sup>3<\/sup>para la bomba elevadora junto al Canal Civit; 300 m<sup>2<\/sup>de pirca en los caminos; 140 m. de caminos y 1.700 m de barandas r\u00fasticas borde\u00e1ndolos y 130 bancos de piedra y de madera. Para los animales se han construido 10 jaulas y 10 corrales. Finalmente el zool\u00f3gico ha sido forestado con 5.000 \u00e1rboles y se han sembrado 11.000 m<sup>2<\/sup>de u\u00f1a de le\u00f3n y plantas florales en los taludes.<a><sup>[5]<\/sup><\/a><\/p>\n<p>Desde 1943 hasta 1946 es fecundo en realizaciones y en la obtenci\u00f3n de nuevos ejemplares. Se realizan canjes con los zool\u00f3gicos de Buenos Aires, La Plata, C\u00f3rdoba y Santiago de Chile. Tambi\u00e9n se adquirieron animales a particulares, entre ellos la empresa de Hollywood Park. De nuestro Zoo tambi\u00e9n se exportan animales.<a><sup>[6]<\/sup><\/a><\/p>\n<p>Tal movimiento de animales plantea la necesidad de construir recintos apropiados para alojarlos, con grutas, bebederos y las comodidades indispensables. Se ampl\u00eda la jaula de los c\u00f3ndores, se construye la de los jaguares, el recinto para los elefantes y el de los ciervos.<a><sup>[7]<\/sup><\/a><\/p>\n<p>Para el p\u00fablico visitante se construye un nuevo grupo sanitario en las cercan\u00edas de las jaulas de los c\u00f3ndores. Dos a\u00f1os antes se hab\u00eda instalado un kiosco para venta de comestibles, revistas, postales y recuerdos de Mendoza. Hacia fines de 1945 hay una nueva autorizaci\u00f3n para construir caminos interiores.<a><sup>[8]<\/sup><\/a><\/p>\n<p>El chalet funcion\u00f3 como lugar de veraneo de los gobernadores hasta poco despu\u00e9s de 1930, que adquiri\u00f3 otros usos: seg\u00fan Jos\u00e9 Benito de San Mart\u00edn fue cedido por el gobernador Ricardo Videla para los hu\u00e9rfanos del asilo ubicado en el Parque.<a><sup>[9]<\/sup><\/a><\/p>\n<p>Dentro del plan de mejoras del parque, el gobierno dispone convertir el chalet del Cerro en hoster\u00eda. En 1940 se hacen los estudios y se llevan a cabo los trabajos. A finales de 1941, mientras se tramitaba el contrato de concesi\u00f3n, la Direcci\u00f3n de Arquitectura realiza por administraci\u00f3n una serie de refacciones y ampliaciones en el edificio. En enero de 1942 se firma contrato para su explotaci\u00f3n comercial. Hacia 1946 deben licitarse nuevas obras de refacci\u00f3n.<\/p>\n<p>Con el transcurso del tiempo, aquella idea original de Ramos Correas de un Parque Zool\u00f3gico con inmejorable belleza y posibilidades de ampliaci\u00f3n, donde se reivindica la naturaleza y el ambiente, se fue transformando a trav\u00e9s de las diferentes gestiones, en un conjunto de recintos y animales para exposici\u00f3n, alter\u00e1ndose su concepci\u00f3n.<\/p>\n<hr class=\"wp-block-separator\" \/>\n<p><a><sup>[1]<\/sup><\/a>Castro, Ana. El Parque General San Mart\u00edn. Sus primeros cincuenta a\u00f1os. JEHM. 1996. pp. 46-51<\/p>\n<p><a><sup>[2]<\/sup><\/a>Listado de obras del Plan de Mejoras: Teatro al aire libre; estadio o anfiteatro; modificaci\u00f3n de las tribunas del lago; parque infantil; parque Zool\u00f3gico al pie del Cerro de la Gloria; Reformas en el Cerro; Mejoras en Av. Uriburu y caminos de acceso al Monumento; extensi\u00f3n del Parque hacia el Norte por Boulogne Sur Mer; modificaci\u00f3n de los jardines de entrada y rotonda de Los Caballos de Marly; remodelaci\u00f3n del Rosedal; utilizaci\u00f3n de los terrenos entre Boulogne Sur Mer y el Jarillal; Expropiaci\u00f3n de terrenos al norte de avenida Uriburu; mejoramiento de terrenos entre canal del oeste y cerro de la gloria; nueva ubicaci\u00f3n edificios de administraci\u00f3n dep\u00f3sitos y talleres; casas para obreros; pavimentaci\u00f3n de calles en el parque y construcci\u00f3n de veredas y pistas para jinetes; modificaci\u00f3n sistemas de iluminaci\u00f3n; traslado de viveros e invern\u00e1culos; vivero provincial; prolongaci\u00f3n de Boulogne Sur Mer al sur y puente sobre el Zanj\u00f3n Fr\u00edas. Castro, Ana. Op. Cit. P\u00e1g. 176.<\/p>\n<p><a><sup>[3]<\/sup><\/a>El Decreto 137\/40 ordena la construcci\u00f3n del nuevo Zool\u00f3gico.<\/p>\n<p><a><sup>[4]<\/sup><\/a>Complemento del Teatro al aire libre Pulgarcito es la confiter\u00eda. Este edificio se construye tomando de base el pabell\u00f3n que ocuparon los leones en el antiguo Zool\u00f3gico. Se conserva gran parte de la estructura del edificio, se ampl\u00eda y se realiza el acceso por la av. De circunvalaci\u00f3n. Las obras se realizan en el a\u00f1o 1944 y 1945. Las empresas constructoras: Salvador Carobene, y la etapa final Julio Pira. El 6 de abril de 1946 se inaugura la hoster\u00eda. Catro, Ana. Op. Cit.<\/p>\n<p><a><sup>[5]<\/sup><\/a>\u00cddem pag. 191.<\/p>\n<p><a><sup>[6]<\/sup><\/a>Ver Registro Oficial. Econom\u00eda, Obras P\u00fablicas y Riego. Del a\u00f1o 1941 al 1945. En Castro, Ana. Op. Cit.<\/p>\n<p><a><sup>[7]<\/sup><\/a>\u00cddem P\u00e1g. 191.<\/p>\n<p><a><sup>[8]<\/sup><\/a>Ib\u00eddem.<\/p>\n<p><a><sup>[9]<\/sup><\/a>Ver Benito de San Martin 1940, p. 251. Citado por Favre Patricia. 2015.<\/p>\n<p>[\/et_pb_tab][et_pb_tab title=\u00bbMaster plan, ideas y proyecto\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_enable_image=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>Master plan, ideas y proyecto<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/mza-dicaws-portal-uploads-media-prod.s3.us-east-1.amazonaws.com\/informacion-oficial\/uploads\/sites\/12\/2025\/04\/SV_L5_-_Concurso_Ecoparque_Mendoza_361315_J-300x292.jpg\" width=\"300\" height=\"292\" alt=\"\" class=\"wp-image-516 alignnone size-medium\" \/><\/p>\n<p>En diciembre de 2017 se llam\u00f3 al Concurso Nacional de Master Plan, Ideas y Anteproyecto para el nuevo Ecoparque Mendoza. El objetivo general fue obtener propuestas para transformar el predio y el entorno inmediato del ex Parque Zool\u00f3gico en el actual Ecoparque, definido por\u00a0<a href=\"https:\/\/www.argentina.gob.ar\/normativa\/provincial\/ley-8945-123456789-0abc-defg-549-8000mvorpyel\">Ley Provincial 8945<\/a><span>\u00a0<\/span>y\u00a0<a href=\"http:\/\/www.saij.gob.ar\/451-local-mendoza-decreto-reglamentario-ley-8945-crean-direccion-ecoparque-mendoza-direccion-parques-paseos-publicos-m20170000451-2017-04-04\/123456789-0abc-154-0000-7102mvorpced?utm_source=newsletter-semanal&amp;utm_medium=email&amp;utm_term=semanal&amp;utm_campaign=decreto-provincial\">Decreto Reglamentario 451\/2017<\/a>y en una segunda prueba, un Anteproyecto para concebir los edificios y refuncionalizar los senderos y lugares de esparcimiento necesarios en una primera etapa de concreci\u00f3n, acorde a lo definido por las bases del Concurso.<\/p>\n<p>Las propuestas debieron interpretar y reflejar el cambio de paradigma en la forma relacionarse con los animales, la flora y el ambiente en general, entendiendo que todos los seres que habitamos este planeta somos uno, que estamos conectados y debemos restablecer los equilibrios que el hombre ha colapsado en el \u00faltimo siglo, respetando a su vez el car\u00e1cter hist\u00f3rico patrimonial del predio tanto en el espacio que se inserta, como en los componentes que se relacionan directa o indirectamente con el paisaje construido a trav\u00e9s del tiempo.<\/p>\n<p>El Ecoparque Mendoza ser\u00e1 un espacio inspirador, que invitar\u00e1 a los visitantes a volver a conectarse con la naturaleza a trav\u00e9s de su magn\u00edfica forestaci\u00f3n y las especies que habitan libres en el predio, un espacio educador, que mostrar\u00e1 herramientas y estrategias de vanguardia en la protecci\u00f3n del ambiente, y ser\u00e1 la cara de Mendoza al mundo, siendo el disparador para que turistas y mendocinos decidan conocer m\u00e1s acerca de los recursos naturales de la Provincia, a partir del conocimiento de su historia y el esp\u00edritu vanguardista en la b\u00fasqueda de la sustentabilidad en el uso de los recursos. En este espacio la prioridad ser\u00e1 respetar la vida en todas sus formas y velar por su bienestar, lo que implica emitir un potente llamado a cuidar los h\u00e1bitats naturales. El concepto de \u201cmuestrario de animales\u201d del antiguo Zool\u00f3gico se reemplaza por el de \u201cprotecci\u00f3n de todas las formas de vida y en particular, de las especies aut\u00f3ctonas en peligro de extinci\u00f3n.\u201d El hombre en equilibrio con el ambiente, consciente de su historia y protagonista de los cambios que el siglo XXI requiere.<\/p>\n<p>En abril de 2018 se seleccion\u00f3 el proyecto ganador del nuevo Ecoparque Mendoza, un trabajo realizado por Lesch Guillermo y Alfaro Leticia. Y finalmente en diciembre de 2019, dicho proyecto adem\u00e1s, es reconocido con el 1\u00ba Premio Nacional de Arquitectura y Dise\u00f1o Urbano Sustentable.<\/p>\n<p>La presentaci\u00f3n del proyecto de reconversi\u00f3n tambi\u00e9n incluy\u00f3 el desarrollo de un cambio de identidad gr\u00e1fica \u2013es decir el dise\u00f1o de una nueva marca\u2013que tom\u00f3 como fuente en informaci\u00f3n y basamento conceptual no solamente la idea de un cambio de nombre sino la noci\u00f3n de un cambio profundo de paradigma.<\/p>\n<p>La nueva marca asumi\u00f3 el desaf\u00edo de mostrar a trav\u00e9s de la s\u00edntesis este nuevo concepto de paseo ambiental a trav\u00e9s de \u00edconos de los elementos naturales como el agua, el aire, la flora y la fauna. El \u00edcono se compuso a trav\u00e9s de l\u00edneas curvas y entrelazadas que dan idea de fluidez, propia del mundo natural en general, y la idea de \u201clo circular\u201d propio del cerro que es el h\u00e1bitat del proyecto Ecoparque.<\/p>\n<p><a href=\"https:\/\/www.dropbox.com\/sh\/xkd9n3ij0arykny\/AAA1z5MUMjvyBGpTFoZ0Wtnqa?dl=0\" target=\"_blank\" rel=\"noreferrer noopener\">Bases del Concurso Nacional para el Nuevo Ecoparque Mendoza<\/a><\/p>\n<p><a href=\"https:\/\/www.dropbox.com\/sh\/xkd9n3ij0arykny\/AAA1z5MUMjvyBGpTFoZ0Wtnqa?dl=0\" target=\"_blank\" rel=\"noreferrer noopener\">Proyecto ganador para el nuevo \u201cEcoparque Mendoza\u201d\u00a0<\/a><\/p>\n<p><a href=\"https:\/\/www.mendoza.gov.ar\/prensa\/el-proyecto-ejecutivo-de-ecoparque-obtuvo-el-1opremio-nacional-de-arquitectura-y-diseno-urbano-sustentable\/\" target=\"_blank\" rel=\"noreferrer noopener\">Ecoparque obtiene el 1\u00ba Premio Nacional de Arquitectura y Dise\u00f1o Urbano Sustentable 2019<\/a><\/p>\n<p><a href=\"https:\/\/www.mendoza.gov.ar\/prensa\/el-proyecto-ecoparque-ganador-de-los-premios-holcim-awards-para-latinoamerica\/\" target=\"_blank\" rel=\"noreferrer noopener\">El Proyecto Ecoparque ganador de Premio Internacional a la Arquitectura Sustentable<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><sup>[6]<\/sup>Ver Registro Oficial. Econom\u00eda, Obras P\u00fablicas y Riego. Del a\u00f1o 1941 al 1945. En Castro, Ana. Op. Cit.<\/p>\n<p><sup>[7]<\/sup>\u00cddem P\u00e1g. 191.<\/p>\n<p><sup>[8]<\/sup>Ib\u00eddem.<\/p>\n<p><sup>[9]<\/sup>Ver Benito de San Martin 1940, p. 251. Citado por Favre Patricia. 2015.<\/p>\n<p>[\/et_pb_tab][et_pb_tab title=\u00bbInforme de Gesti\u00f3n\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_enable_image=\u00bboff\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p><strong>Informe de Gesti\u00f3n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>La\u00a0<a href=\"https:\/\/www.argentina.gob.ar\/normativa\/provincial\/ley-5961-123456789-0abc-defg-169-5000mvorpyel\">Ley Provincial 5.961<\/a><span>\u00a0<\/span>declara de inter\u00e9s las acciones y actividades destinadas a la preservaci\u00f3n, conservaci\u00f3n, defensa y mejoramiento de los ambientes urbanos, agropecuarios y naturales y todos sus elementos constitutivos.<\/p>\n<p>En su Art. 7 la Ley obliga al Poder Ejecutivo, por intermedio de la actual Secretar\u00eda de Ambiente y Ordenamiento Territorial y en coordinaci\u00f3n con los organismos pertinentes, a elevar anualmente a la H. Legislatura un Informe Ambiental, el cual contendr\u00e1 los siguientes aspectos, entre otros:<\/p>\n<ol type=\"a\">\n<li>Estado general de los ecosistemas, ambientes naturales, agropecuarios y urbanos y su equilibrio ecol\u00f3gico;<\/li>\n<li>Situaci\u00f3n de los recursos naturales, renovables, renovables o no, potencialidad productiva, grado de degradaci\u00f3n o contaminaci\u00f3n y perspectivas futuras;<\/li>\n<li>Desarrollo del Plan Ambiental y de los distintos programas en ejecuci\u00f3n;<\/li>\n<li>Evaluaci\u00f3n cr\u00edtica de lo actuado, enmiendas a efectuar y propuestas de soluci\u00f3n.<\/li>\n<\/ol>\n<p>El Informe Ambiental, describe la labor desarrollada anualmente por la Direcci\u00f3n Ecoparque Mendoza.<\/p>\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-subsecretaria-de-ambiente\">\n<div class=\"wp-block-embed__wrapper\"><\/div>\n<\/figure>\n<p>[\/et_pb_tab][\/et_pb_tabs][\/et_pb_column][\/et_pb_row][et_pb_row module_id=\u00bbbienestar\u00bb _builder_version=\u00bb4.27.4&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb min_height=\u00bb117px\u00bb custom_margin=\u00bb0px|auto|-3px|auto||\u00bb custom_padding=\u00bb5px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_slider _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_font_size=\u00bb1.5rem\u00bb body_text_align=\u00bbleft\u00bb body_text_color=\u00bb#ffffff\u00bb background_color=\u00bbrgba(10,10,10,0.3)\u00bb button_alignment=\u00bbcenter\u00bb max_width=\u00bb800px\u00bb module_alignment=\u00bbcenter\u00bb min_height=\u00bb559.2px\u00bb custom_margin=\u00bb||||false|false\u00bb custom_padding=\u00bb29px||62px||false|false\u00bb border_radii=\u00bbon|8px|8px|8px|8px\u00bb global_colors_info=\u00bb{%22gcid-d91e32a4-ea1b-4f3a-9581-0fb489560a1a%22:%91%22body_text_color%22%93}\u00bb][et_pb_slide heading=\u00bbBienestar Animal\u00bb button_text=\u00bbLey 8.945&#8243; button_link=\u00bbhttps:\/\/www.saij.gob.ar\/8945-local-mendoza-crean-direccion-ecoparque-mendoza-direccion-parques-paseos-publicos-lpm0008945-2016-12-27\/123456789-0abc-defg-549-8000mvorpyel\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>Las acciones para el aseguramiento del bienestar animal se concentran en tres actividades: a) la derivaci\u00f3n de animales a nuevos hogares donde gozar\u00e1n de mejor calidad de vida, b) la rehabilitaci\u00f3n de animales de la fauna nativa que han sufrido alg\u00fan trauma en el medio natural y necesitan asistencia, y c) el control de natalidad dentro del Ecoparque para evitar el aumento de la poblaci\u00f3n, y d) el plan sanitario aplicado en el Ecoparque, para reforzar las defensas y asegurar una mejor calidad de vida, ya sea dentro o fuera de las instalaciones. Esto se complementa con una calidad en la nutrici\u00f3n y la mejora constante de los recintos.<\/p>\n<ul><\/ul>\n<p>La <a href=\"https:\/\/www.argentina.gob.ar\/normativa\/provincial\/ley-8945-123456789-0abc-defg-549-8000mvorpyel\"><span style=\"color: #0091f2\">Ley Provincial 8945<\/span><\/a> proh\u00edbe la compra\/venta y canje de animales con otras instituciones p\u00fablicas o privadas, nacionales o extranjeras, y\/o particulares.<\/p>\n<ul><\/ul>\n<p>[\/et_pb_slide][et_pb_slide heading=\u00bbBienestar Animal\u00bb button_text=\u00bbDecreto 451&#8243; button_link=\u00bbhttps:\/\/www.saij.gob.ar\/451-local-mendoza-decreto-reglamentario-ley-8945-crean-direccion-ecoparque-mendoza-direccion-parques-paseos-publicos-m20170000451-2017-04-04\/123456789-0abc-154-0000-7102mvorpced?utm_source=newsletter-semanal&amp;utm_medium=email&amp;utm_term=semanal&amp;utm_campaign=decreto-provincial\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>El Ecoparque s\u00f3lo recepciona animales provenientes de los procedimientos de aplicaci\u00f3n de las leyes de protecci\u00f3n de fauna silvestre y animales que ingresen como planteles de cr\u00eda de la fauna aut\u00f3ctona, cuya entrada est\u00e9 enmarcada en programas de conservaci\u00f3n debidamente aprobados y vigentes de la Direcci\u00f3n del Ecoparque.<\/p>\n<p>La poblaci\u00f3n de animales, a diciembre de 2024, estaba integrada por 1.194 individuos de los cuales: 261 corresponden a individuos de especies ex\u00f3ticas; 810 corresponden a individuos de especies de corral; 104 corresponden a individuos de especies aut\u00f3ctonas mendocinas; y 19 corresponden a individuos de especies aut\u00f3ctonas argentinas.<\/p>\n<p>[\/et_pb_slide][\/et_pb_slider][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbRGBA(255,255,255,0)\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb360deg\u00bb background_color_gradient_stops=\u00bbrgba(209,209,209,0.04) 0%|#c4c4c4 100%\u00bb max_width=\u00bb2560px\u00bb border_radii=\u00bbon|10px|10px|10px|10px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_number_counter title=\u00bbPOBLACI\u00d3N DE ANIMALES A JULIO DE 2025&#8243; number=\u00bb1.128&#8243; percent_sign=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|700|||||||\u00bb title_text_color=\u00bbgcid-840cd285-ee6f-49c1-abc9-5e893f3235b8&#8243; title_font_size=\u00bb2rem\u00bb number_font=\u00bb|700|||||||\u00bb number_text_color=\u00bb#0C71C3&#8243; global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22title_text_color%22%93}\u00bb title_letter_spacing__hover_enabled=\u00bbon|desktop\u00bb][\/et_pb_number_counter][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(137,137,137,0.18)\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_stops=\u00bbrgba(209,209,209,0.04) 0%|#c4c4c4 100%\u00bb max_width=\u00bb2560px\u00bb custom_margin=\u00bb|auto|-24px|auto||\u00bb border_radii=\u00bbon|10px|10px|10px|10px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_number_counter title=\u00bbESPECIES EX\u00d3TICAS\u00bb number=\u00bb250&#8243; percent_sign=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|300|||||||\u00bb title_text_color=\u00bb#000000&#8243; number_text_color=\u00bb#0C71C3&#8243; number_font_size=\u00bb4rem\u00bb background_layout=\u00bbdark\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22title_text_color%22%93}\u00bb][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_number_counter title=\u00bbESPECIES DE CORRAL\u00bb number=\u00bb734&#8243; percent_sign=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|300|||||||\u00bb title_text_color=\u00bb#000000&#8243; number_text_color=\u00bb#0C71C3&#8243; number_font_size=\u00bb4rem\u00bb background_layout=\u00bbdark\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22title_text_color%22,%22title_text_color%22%93}\u00bb][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_number_counter title=\u00bbESPECIES AUT\u00d3CTONAS MENDOCINAS\u00bb number=\u00bb115&#8243; percent_sign=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|300|||||||\u00bb title_text_color=\u00bb#000000&#8243; number_text_color=\u00bb#0C71C3&#8243; number_font_size=\u00bb4rem\u00bb background_layout=\u00bbdark\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22title_text_color%22,%22title_text_color%22%93}\u00bb][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_number_counter title=\u00bbESPECIES AUT\u00d3CTONAS ARGENTINAS\u00bb number=\u00bb39&#8243; percent_sign=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|300|||||||\u00bb title_text_color=\u00bb#000000&#8243; number_text_color=\u00bb#0C71C3&#8243; number_font_size=\u00bb4rem\u00bb background_layout=\u00bbdark\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22title_text_color%22%93}\u00bb][\/et_pb_number_counter][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,3_4&#8243; module_id=\u00bbcorral\u00bb _builder_version=\u00bb4.27.4&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb max_width=\u00bb2560px\u00bb min_height=\u00bb404.7px\u00bb custom_margin=\u00bb|auto|-3px|auto||\u00bb custom_padding=\u00bb5px|0px|4px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/mza-dicaws-portal-uploads-media-prod.s3.us-east-1.amazonaws.com\/informacion-oficial\/uploads\/sites\/12\/2025\/06\/IMG_0797-scaled.jpg\u00bb title_text=\u00bbIMG_0797&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb max_width=\u00bb350px\u00bb custom_margin=\u00bb78px|24px|||false|false\u00bb custom_padding=\u00bb45px|0px||||\u00bb border_radii=\u00bbon|14px|14px|14px|14px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|300|||||||\u00bb title_text_color=\u00bbgcid-bb9c0857-25e3-4051-b4b2-87f09afe6b01&#8243; min_height=\u00bb24px\u00bb custom_padding=\u00bb0px|||||\u00bb global_colors_info=\u00bb{%22gcid-bb9c0857-25e3-4051-b4b2-87f09afe6b01%22:%91%22title_text_color%22%93}\u00bb][\/et_pb_heading][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_text_color=\u00bbgcid-d91e32a4-ea1b-4f3a-9581-0fb489560a1a\u00bb text_font_size=\u00bb16px\u00bb background_color=\u00bbrgba(0,0,0,0.11)\u00bb text_orientation=\u00bbjustified\u00bb width=\u00bb100%\u00bb max_width=\u00bb800px\u00bb module_alignment=\u00bbright\u00bb min_height=\u00bb329.7px\u00bb custom_margin=\u00bb|-23px|46px|37px||\u00bb custom_padding=\u00bb27px|28px||29px||\u00bb border_radii=\u00bbon|10px|10px|10px|10px\u00bb global_colors_info=\u00bb{%22gcid-d91e32a4-ea1b-4f3a-9581-0fb489560a1a%22:%91%22text_text_color%22%93}\u00bb]<\/p>\n<h3 style=\"text-align: left\">Animales de Corral<\/h3>\n<p>&nbsp;<\/p>\n<p>Los animales dom\u00e9sticos de corral se encuentran involucrados en el <span style=\"color: #0c71c3\"><a href=\"https:\/\/atencionciudadana.mendoza.gob.ar\/adopcion-responsable-de-animales-de-corral\/\" style=\"color: #0c71c3\">Programa de Adopci\u00f3n Responsable<\/a><\/span> regulado por la<strong> <span><a href=\"https:\/\/drive.google.com\/file\/d\/1-BI2TN-AGlrnQ3xMWlm-sr5xqcTrUG7r\/view?usp=sharing\">Resoluci\u00f3n 48\/18<\/a><\/span><\/strong> de la Secretar\u00eda de Ambiente y Ordenamiento Territorial. En total, desde 2018 a la actualidad, se han entregado 1.414 animales a 79 adoptantes. En ese per\u00edodo se recibieron 535 postulaciones, de las que hasta el d\u00eda de la fecha se ha evaluado el 92% y s\u00f3lo el 18% ha cumplimentado con el procedimiento estipulado por la Resoluci\u00f3n.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(137,137,137,0.18)\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb360deg\u00bb background_color_gradient_stops=\u00bbrgba(209,209,209,0.04) 0%|#c4c4c4 100%\u00bb max_width=\u00bb2560px\u00bb border_radii=\u00bbon|10px|10px|10px|10px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_number_counter title=\u00bbANIMALES INVOLUCRADOS EN EL PROGRAMA DE ADOPCI\u00d3N RESPONSABLE (Desde 2017 a junio de 2025)\u00bb number=\u00bb2.136&#8243; percent_sign=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|700|||||||\u00bb title_text_color=\u00bbgcid-840cd285-ee6f-49c1-abc9-5e893f3235b8&#8243; title_font_size=\u00bb2rem\u00bb number_font=\u00bb|700|||||||\u00bb number_text_color=\u00bb#0C71C3&#8243; global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22title_text_color%22%93}\u00bb title_letter_spacing__hover_enabled=\u00bbon|desktop\u00bb][\/et_pb_number_counter][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(137,137,137,0.18)\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_stops=\u00bbrgba(209,209,209,0.04) 0%|#c4c4c4 100%\u00bb max_width=\u00bb2560px\u00bb border_radii=\u00bbon|10px|10px|10px|10px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_number_counter title=\u00bbANIMALES CON ADOPTANTE ASIGNADO\u00bb number=\u00bb1.493&#8243; percent_sign=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|300|||||||\u00bb title_text_color=\u00bb#000000&#8243; number_text_color=\u00bb#0C71C3&#8243; number_font_size=\u00bb4rem\u00bb background_layout=\u00bbdark\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22title_text_color%22,%22title_text_color%22%93}\u00bb][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_number_counter title=\u00bbANIMALES ADOPTADOS\u00bb number=\u00bb1.454&#8243; percent_sign=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|300|||||||\u00bb title_text_color=\u00bb#000000&#8243; number_text_color=\u00bb#0C71C3&#8243; number_font_size=\u00bb4rem\u00bb background_layout=\u00bbdark\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22title_text_color%22,%22title_text_color%22%93}\u00bb][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_number_counter title=\u00bbADOPTANTES POSTULADOS\u00bb number=\u00bb 536&#8243; percent_sign=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|300|||||||\u00bb title_text_color=\u00bb#000000&#8243; number_text_color=\u00bb#0C71C3&#8243; number_font_size=\u00bb4rem\u00bb background_layout=\u00bbdark\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22title_text_color%22,%22title_text_color%22%93}\u00bb][\/et_pb_number_counter][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_number_counter title=\u00bbADOPTANTES EVALUADOS\u00bb number=\u00bb496&#8243; percent_sign=\u00bboff\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_font=\u00bb|300|||||||\u00bb title_text_color=\u00bb#000000&#8243; number_text_color=\u00bb#0C71C3&#8243; number_font_size=\u00bb4rem\u00bb background_layout=\u00bbdark\u00bb global_colors_info=\u00bb{%22gcid-840cd285-ee6f-49c1-abc9-5e893f3235b8%22:%91%22title_text_color%22,%22title_text_color%22%93}\u00bb][\/et_pb_number_counter][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb2560px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_button button_url=\u00bbhttps:\/\/atencionciudadana.mendoza.gob.ar\/adopcion-responsable-de-animales-de-corral\/\u00bb url_new_window=\u00bbon\u00bb button_text=\u00bbPOSTULATE PARA ADOPTAR\u00bb button_alignment=\u00bbcenter\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_button=\u00bbon\u00bb button_text_size=\u00bb41px\u00bb button_bg_color=\u00bbrgba(0,0,0,0.25)\u00bb background_layout=\u00bbdark\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_button][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,3_4&#8243; module_id=\u00bbexoticos\u00bb _builder_version=\u00bb4.27.4&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb max_width=\u00bb2560px\u00bb min_height=\u00bb404.7px\u00bb custom_margin=\u00bb|auto|74px|auto||\u00bb custom_padding=\u00bb5px|0px|4px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_image src=\u00bbhttps:\/\/mza-dicaws-portal-uploads-media-prod.s3.us-east-1.amazonaws.com\/informacion-oficial\/uploads\/sites\/12\/2025\/06\/IMG_9102-scaled.jpg\u00bb title_text=\u00bbIMG_9102&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb max_width=\u00bb320px\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb25px|26px|||false|false\u00bb custom_padding=\u00bb6px|0px||||\u00bb border_radii=\u00bbon|14px|14px|14px|14px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][et_pb_image src=\u00bbhttps:\/\/mza-dicaws-portal-uploads-media-prod.s3.us-east-1.amazonaws.com\/informacion-oficial\/uploads\/sites\/12\/2025\/06\/IMG_9925-scaled.jpg\u00bb title_text=\u00bbIMG_9925&#8243; _builder_version=\u00bb4.27.2&#8243; _module_preset=\u00bbdefault\u00bb width=\u00bb100%\u00bb max_width=\u00bb320px\u00bb module_alignment=\u00bbcenter\u00bb custom_margin=\u00bb1px|26px|||false|false\u00bb custom_padding=\u00bb0px|0px|||false|false\u00bb border_radii=\u00bbon|14px|14px|14px|14px\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_image][\/et_pb_column][et_pb_column type=\u00bb3_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_slider _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb header_font_size=\u00bb1.5rem\u00bb body_text_align=\u00bbleft\u00bb background_color=\u00bbrgba(10,10,10,0.3)\u00bb button_alignment=\u00bbcenter\u00bb max_width=\u00bb1200px\u00bb module_alignment=\u00bbleft\u00bb min_height=\u00bb559.2px\u00bb custom_margin=\u00bb|||0px|false|false\u00bb custom_padding=\u00bb0px||0px|4px|false|false\u00bb border_radii=\u00bbon|8px|8px|8px|8px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_slide heading=\u00bbAnimales ex\u00f3ticos y aut\u00f3ctonos argentinos\u00bb button_text=\u00bbLey 8.945&#8243; button_link=\u00bbhttps:\/\/www.argentina.gob.ar\/normativa\/provincial\/ley-8945-123456789-0abc-defg-549-8000mvorpyel\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>Los animales ex\u00f3ticos o aut\u00f3ctonos de otras zonas del pa\u00eds son derivados, en la medida de lo posible, a lugares especializados que les provean mejor calidad de vida y un clima y h\u00e1bitat acordes a las necesidades de su especie. Al respecto, entre las derivaciones m\u00e1s \u00e9picas podemos mencionar el traslado de Cecilia, la chimpanc\u00e9, al Santuario de \u201cProyecto Gran Simio\u201d en Brasil; el traslado de Salte\u00f1a y Chupino, 2 leones africanos, a \u201cThe WildCat Sanctuary\u201d en Estados Unidos; el reciente traslado de Mabel, Sorpresa, Julieta, Rosa y sus hermanas Esperanza y Libertad, Athila, Fausto, Buko y Yogi,10 osos pardos a \u201cThe Wildlife Animal Sanctuary\u201d tambi\u00e9n en Estados Unidos; el traslado de 3 tucanes a la Reserva Natural \u201cHorco Molle\u201d en la Provincia de Tucum\u00e1n, en el norte argentino; el traslado de 2 tapires y m\u00e1s de 80 pecar\u00edes de collar al Parque Nacional \u201cIber\u00e1\u201d en la Provincia de Corrientes, tambi\u00e9n en el norte argentino.<\/p>\n<p>&nbsp;<\/p>\n<ul><\/ul>\n<p>[\/et_pb_slide][et_pb_slide heading=\u00bbAnimales aut\u00f3ctonos mendocinos\u00bb button_link=\u00bbhttps:\/\/www.mendoza.gov.ar\/ecoparque\/wp-content\/uploads\/sites\/35\/2018\/03\/Decreto-reglamentario-451.pdf\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p>&nbsp;<\/p>\n<p>Los animales de la fauna aut\u00f3ctona mendocina, en la medida de lo posible, son incorporados en programas de rehabilitaci\u00f3n para su posterior reconstituci\u00f3n en el h\u00e1bitat natural. En 2020, la Direcci\u00f3n Ecoparque Mendoza inici\u00f3 las acciones para el trabajo en rehabilitaci\u00f3n con tres especies emblem\u00e1ticas mendocinas: el c\u00f3ndor, el puma, y el \u00e1guila coronada. Asimismo, desde 2016 se trabaja con aves rapaces peque\u00f1as como gavilanes mixtos y caranchos, y tambi\u00e9n con guanacos.<\/p>\n<p>[\/et_pb_slide][et_pb_slide heading=\u00bbControl sanitario\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p>En referencia al plan sanitario, se hace un muestreo peri\u00f3dico de ovinos, caprinos, equinos y bubalinos para evaluar su estado sanitario antes de darlos en adopci\u00f3n. Desde 2018, la cifra de muestreos asciende a 2.011.<\/p>\n<p>Anualmente, desde 2016, se realiza la vacunaci\u00f3n antiaftosa de todos los b\u00fafalos (47) y contra la brucelosis de las hembras juveniles (2). Tambi\u00e9n se han realizado vacunaciones preventivas de neumon\u00eda en ovinos y caprinos, totalizando 1010 vacunas aplicadas.<\/p>\n<p>[\/et_pb_slide][et_pb_slide heading=\u00bbControl de natalidad\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb sticky_transition=\u00bbon\u00bb]<\/p>\n<p>Desde 2016, se ha implementado la separaci\u00f3n por sexo de las especies, a los efectos de detener la reproducci\u00f3n de los animales en el predio. Dependiendo de las especies, esto signific\u00f3 habilitar nuevos recintos para los animales a separar, o bien, dividir recintos existentes en la medida en que el espacio disponible fuera suficiente. El avance de los traslados de los animales permiti\u00f3 disponer de mayores espacios y con ello, acelerar la separaci\u00f3n por sexo de las especies.<\/p>\n<p>En 2020 el Servicio Veterinario del Ecoparque desarroll\u00f3 una propuesta para un programa de castraci\u00f3n de machos de c\u00e9rvidos y muflones de C\u00f3rcega, especies ex\u00f3ticas invasoras, que comenz\u00f3 a implementarse este a\u00f1o. El programa aplica una t\u00e9cnica poco invasiva y cuenta con la participaci\u00f3n de m\u00e9dicos veterinarios voluntarios, a trav\u00e9s del Programa de Voluntariado del Ecoparque Mendoza. La poblaci\u00f3n de c\u00e9rvidos y muflones es de 700 individuos en el Ecoparque. La castraci\u00f3n permitir\u00e1 derivar a estos individuos en forma segura a otros centros, con el acuerdo y bajo la supervisi\u00f3n de la Direcci\u00f3n de Recursos Naturales Renovables.. Similar t\u00e9cnica de castraci\u00f3n ha sido ensayada y se aplicar\u00e1 en monos papiones luego de finalizar el trabajo con c\u00e9rvidos y muflones. Se lleva adelante tambi\u00e9n la castraci\u00f3n de machos de cobayos de la India.<\/p>\n<p>[\/et_pb_slide][\/et_pb_slider][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_5,1_5,1_5,1_5,1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb background_color=\u00bbrgba(137,137,137,0.18)\u00bb use_background_color_gradient=\u00bbon\u00bb background_color_gradient_direction=\u00bb360deg\u00bb background_color_gradient_stops=\u00bbrgba(209,209,209,0.04) 0%|#c4c4c4 100%\u00bb max_width=\u00bb2560px\u00bb border_radii=\u00bbon|10px|10px|10px|10px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_icon font_icon=\u00bb&#xf1b0;||fa||900&#8243; icon_color=\u00bb#0C71C3&#8243; url=\u00bbhttps:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/cecilia-2&#8243; url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||5%||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][et_pb_heading title=\u00bbCecilia\u00bb url=\u00bbhttps:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/cecilia-2&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh5&#8243; title_text_align=\u00bbcenter\u00bb custom_margin=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_icon font_icon=\u00bb&#xf1b0;||fa||900&#8243; icon_color=\u00bb#0C71C3&#8243; url=\u00bbhttps:\/\/www.mendoza.gov.ar\/prensa\/los-leones-del-ecoparque-fueron-trasladados-a-un-santuario-natural-en-estados-unidos\/\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||5%||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][et_pb_heading title=\u00bbLeones\u00bb url=\u00bbhttps:\/\/www.mendoza.gov.ar\/prensa\/los-leones-del-ecoparque-fueron-trasladados-a-un-santuario-natural-en-estados-unidos\/\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh5&#8243; title_text_align=\u00bbcenter\u00bb custom_margin=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_icon font_icon=\u00bb&#xf1b0;||fa||900&#8243; icon_color=\u00bb#0C71C3&#8243; url=\u00bbhttps:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/tigres\/\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||5%||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][et_pb_heading title=\u00bbLucy la Tigresa\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh5&#8243; title_text_align=\u00bbcenter\u00bb custom_margin=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_icon font_icon=\u00bb&#xf1b0;||fa||900&#8243; icon_color=\u00bb#0C71C3&#8243; url=\u00bbhttps:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/osos\/\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||5%||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][et_pb_heading title=\u00bbOsos\u00bb url=\u00bbhttps:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/osos\/\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh5&#8243; title_text_align=\u00bbcenter\u00bb custom_margin=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_icon font_icon=\u00bb&#xf1b0;||fa||900&#8243; icon_color=\u00bb#0C71C3&#8243; url=\u00bbhttps:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/elefantes\/\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||5%||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][et_pb_heading title=\u00bbElefantes\u00bb url=\u00bbhttps:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/elefantes\/\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh5&#8243; title_text_align=\u00bbcenter\u00bb custom_margin=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_5,1_5,1_5,1_5,1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb2560px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_icon font_icon=\u00bb&#xf1b0;||fa||900&#8243; icon_color=\u00bb#0C71C3&#8243; url=\u00bbhttps:\/\/www.mendoza.gov.ar\/ecoparque\/pecaries-y-tapires-el-viaje-a-los-esteros-de-ibera\/\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||5%||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][et_pb_heading title=\u00bbPecar\u00edes y Tapires\u00bb url=\u00bbhttps:\/\/www.mendoza.gov.ar\/ecoparque\/pecaries-y-tapires-el-viaje-a-los-esteros-de-ibera\/\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh5&#8243; title_text_align=\u00bbcenter\u00bb custom_margin=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_icon font_icon=\u00bb&#xf1b0;||fa||900&#8243; icon_color=\u00bb#0C71C3&#8243; url=\u00bbhttps:\/\/www.mendoza.gov.ar\/prensa\/ecoparque-continuan-las-derivaciones-de-animales-exoticos-a-santuarios-naturales\/\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||5%||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][et_pb_heading title=\u00bbTucanes\u00bb url=\u00bbhttps:\/\/www.mendoza.gov.ar\/prensa\/ecoparque-continuan-las-derivaciones-de-animales-exoticos-a-santuarios-naturales\/\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh5&#8243; title_text_align=\u00bbcenter\u00bb custom_margin=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_icon font_icon=\u00bb&#xf1b0;||fa||900&#8243; icon_color=\u00bb#0C71C3&#8243; url=\u00bbhttps:\/\/www.mendoza.gov.ar\/prensa\/en-el-dia-internacional-del-mono-se-pone-en-valor-el-proyecto-caraya-de-ecoparque\/\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||5%||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][et_pb_heading title=\u00bbMonos Caray\u00e1\u00bb url=\u00bbhttps:\/\/www.mendoza.gov.ar\/prensa\/en-el-dia-internacional-del-mono-se-pone-en-valor-el-proyecto-caraya-de-ecoparque\/\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh5&#8243; title_text_align=\u00bbcenter\u00bb custom_margin=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_icon font_icon=\u00bb&#xf1b0;||fa||900&#8243; icon_color=\u00bb#0C71C3&#8243; url=\u00bbhttps:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/monos-cai\/\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||5%||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][et_pb_heading title=\u00bbMonos Ca\u00ed\u00bb url=\u00bbhttps:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/monos-cai\/\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh5&#8243; title_text_align=\u00bbcenter\u00bb custom_margin=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][et_pb_column type=\u00bb1_5&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_icon font_icon=\u00bb&#xf1b0;||fa||900&#8243; icon_color=\u00bb#0C71C3&#8243; url=\u00bbhttps:\/\/www.mendoza.gov.ar\/prensa\/el-ecoparque-finalizo-la-obra-de-reconversion-del-ex-jirafario-en-un-entorno-pensado-para-el-bienestar-de-los-monos-papiones\/\u00bb url_new_window=\u00bbon\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb custom_margin=\u00bb||5%||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_icon][et_pb_heading title=\u00bbMonos Papiones\u00bb url=\u00bbhttps:\/\/www.mendoza.gov.ar\/prensa\/el-ecoparque-finalizo-la-obra-de-reconversion-del-ex-jirafario-en-un-entorno-pensado-para-el-bienestar-de-los-monos-papiones\/\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh5&#8243; title_text_align=\u00bbcenter\u00bb custom_margin=\u00bb||||false|false\u00bb global_colors_info=\u00bb{}\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb2560px\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_heading title=\u00bbLEGISLACI\u00d3N\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb title_level=\u00bbh3&#8243; title_font=\u00bb|300|||||||\u00bb title_text_color=\u00bbgcid-body-color\u00bb title_font_size=\u00bb1.5rem\u00bb background_color=\u00bbRGBA(255,255,255,0.65)\u00bb min_height=\u00bb49px\u00bb custom_margin=\u00bb40px||-2px|||\u00bb custom_padding=\u00bb11px||3px|30px||\u00bb border_radii=\u00bbon|8px|8px|8px|8px\u00bb global_colors_info=\u00bb{%22gcid-body-color%22:%91%22title_text_color%22%93}\u00bb][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=\u00bb1_4,1_4,1_4,1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb max_width=\u00bb2560px\u00bb custom_margin=\u00bb23px|auto|33px|auto||\u00bb custom_padding=\u00bb2px||5px|||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb0.85rem\u00bb text_line_height=\u00bb1rem\u00bb background_color=\u00bbrgba(255,255,255,0.5)\u00bb min_height=\u00bb92px\u00bb custom_margin=\u00bb||11px|||\u00bb custom_padding=\u00bb||0px|||\u00bb link_option_url=\u00bbhttps:\/\/www.saij.gob.ar\/8945-local-mendoza-crean-direccion-ecoparque-mendoza-direccion-parques-paseos-publicos-lpm0008945-2016-12-27\/123456789-0abc-defg-549-8000mvorpyel\u00bb link_option_url_new_window=\u00bbon\u00bb border_radii=\u00bbon|8px|8px|8px|8px\u00bb border_width_all=\u00bb15px\u00bb border_color_all=\u00bbRGBA(255,255,255,0)\u00bb border_style_all=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center\"><strong>Creaci\u00f3n Ecoparque<\/strong><\/p>\n<p style=\"text-align: center\">Ley 8.945\/16<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb0.85rem\u00bb text_line_height=\u00bb1rem\u00bb background_color=\u00bbrgba(255,255,255,0.5)\u00bb min_height=\u00bb92px\u00bb custom_margin=\u00bb||11px|||\u00bb custom_padding=\u00bb||0px|||\u00bb link_option_url=\u00bbhttps:\/\/www.saij.gob.ar\/451-local-mendoza-decreto-reglamentario-ley-8945-crean-direccion-ecoparque-mendoza-direccion-parques-paseos-publicos-m20170000451-2017-04-04\/123456789-0abc-154-0000-7102mvorpced\u00bb link_option_url_new_window=\u00bbon\u00bb border_radii=\u00bbon|8px|8px|8px|8px\u00bb border_width_all=\u00bb15px\u00bb border_color_all=\u00bbRGBA(255,255,255,0)\u00bb border_style_all=\u00bbsolid\u00bb global_colors_info=\u00bb{}\u00bb]<\/p>\n<p style=\"text-align: center\"><strong>Reglamentaci\u00f3n Ecoparque<\/strong><\/p>\n<p style=\"text-align: center\">Dec 451\/17<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb0.85rem\u00bb text_line_height=\u00bb1rem\u00bb background_color=\u00bbrgba(255,255,255,0.5)\u00bb width=\u00bb100%\u00bb min_height=\u00bb92px\u00bb custom_margin=\u00bb||11px|||\u00bb custom_padding=\u00bb||0px|||\u00bb link_option_url=\u00bbhttps:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/35\/2022\/11\/Resolucio%CC%81n-No-512-2022-Declaracio%CC%81n-Intere%CC%81s-Protocolo-de-Adopcio%CC%81n-Responsable-Mendoza.pdf\u00bb border_radii=\u00bbon|8px|8px|8px|8px\u00bb border_width_all=\u00bb15px\u00bb border_color_all=\u00bbRGBA(255,255,255,0)\u00bb border_style_all=\u00bbsolid\u00bb global_colors_info=\u00bb{%22gcid-body-color%22:%91%22border_color_all%22%93}\u00bb]<\/p>\n<p style=\"text-align: center\"><strong>Dec. Inter\u00e9s \u00abAdopci\u00f3n Responsable\u00bb<\/strong><\/p>\n<p style=\"text-align: center\">Res 512\/22<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=\u00bb1_4&#8243; _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb text_font_size=\u00bb0.85rem\u00bb text_line_height=\u00bb1rem\u00bb background_color=\u00bbrgba(255,255,255,0.5)\u00bb min_height=\u00bb92px\u00bb custom_margin=\u00bb||11px|||\u00bb custom_padding=\u00bb||0px|||\u00bb link_option_url=\u00bbhttps:\/\/www.mendoza.gov.ar\/wp-content\/uploads\/sites\/35\/2022\/11\/Resolucio%CC%81n-No-514-2022-Declaracio%CC%81n-Intere%CC%81s-Creacio%CC%81n-Dccio%CC%81n-Ecoparque-Mendoza-y-Dccion-de-Parques-y-Paseos-Pu%CC%81blicos.pdf\u00bb border_radii=\u00bbon|8px|8px|8px|8px\u00bb border_width_all=\u00bb15px\u00bb border_color_all=\u00bbRGBA(255,255,255,0)\u00bb border_style_all=\u00bbsolid\u00bb global_colors_info=\u00bb{%22gcid-body-color%22:%91%22border_color_all%22%93}\u00bb]<\/p>\n<p style=\"text-align: center\"><strong> Dec. Inter\u00e9s \u00abCreaci\u00f3n del Ecoparque\u00bb<\/strong><strong><\/strong><\/p>\n<p style=\"text-align: center\">Res 514\/22<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=\u00bb1&#8243; module_id=\u00bbcontacto\u00bb _builder_version=\u00bb4.27.4&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_row _builder_version=\u00bb4.27.4&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb min_height=\u00bb897.8px\u00bb custom_margin=\u00bb|auto|-163px|auto||\u00bb custom_padding=\u00bb39px|||||\u00bb global_colors_info=\u00bb{}\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.16&#8243; custom_padding=\u00bb|||\u00bb global_colors_info=\u00bb{}\u00bb custom_padding__hover=\u00bb|||\u00bb][et_pb_text _builder_version=\u00bb4.27.4&#8243; text_text_color=\u00bb#000000&#8243; header_text_color=\u00bb#000000&#8243; background_size=\u00bbinitial\u00bb background_position=\u00bbtop_left\u00bb background_repeat=\u00bbrepeat\u00bb min_height=\u00bb603.8px\u00bb custom_margin=\u00bb||-1px|||\u00bb custom_padding=\u00bb||0px|||\u00bb global_colors_info=\u00bb{}\u00bb]<!-- divi:paragraph --><!-- divi:paragraph --><\/p>\n<h3>L\u00edneas telef\u00f3nicas<\/h3>\n<p><strong>Administraci\u00f3n<\/strong><span style=\"color: #0a0a0a;, sans-serif;font-size: 16px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;white-space: nowrap;background-color: #ffffff;display: inline !important;float: none\"><br \/><\/span><span style=\"color: #0a0a0a;, sans-serif;font-size: 16px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;white-space: nowrap;background-color: #ffffff;display: inline !important;float: none\">(261) 423-0295<br \/><\/span><span style=\"color: #0a0a0a;, sans-serif;font-size: 16px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;white-space: nowrap;background-color: #ffffff;display: inline !important;float: none\">(261) 518-2481<\/span><\/p>\n<p>\u200eecoparque@mendoza.gov.ar<\/p>\n<p><strong>Directos<\/strong><\/p>\n<p>Compras (<span style=\"color: #0a0a0a;, sans-serif;font-size: 16px;font-style: normal;font-weight: 400;letter-spacing: normal;text-align: start;text-indent: 0px;text-transform: none;white-space: nowrap;background-color: #ffffff;display: inline !important;float: none\">261) 5185905<\/span><br \/>Programa de Adopci\u00f3n Responsable de animales de corral (261) 6972348<\/p>\n<p>Fauna (261) 750-3417 \/ 7023239\/ 261 7024006)<br \/>de lunes a viernes de 8:00 a 13:00 hs<\/p>\n<p>Vivero\u00a0Notti<br \/>Forestaci\u00f3n\u00a0(261) 4270304<\/p>\n<p>Flora\u00a0Nativa\u00a0(funciona\u00a0en\u00a0la\u00a0sede\u00a0de\u00a0Parques\u00a0y\u00a0Paseos)<br \/>(261) 4290294 \u2013 4294884 (pedir hablar con Flora Nativa \/ Bosque Nativo)<\/p>\n<p>&nbsp;<\/p>\n<p><!-- \/divi:paragraph -->[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En 1896, cuando Mendoza a\u00fan buscaba ensanchar su pecho, alguien imagin\u00f3 lo imposible: que el desierto fuera bosque. As\u00ed naci\u00f3 el Parque del Oeste, para transformar el rigor de la [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":0,"parent":494,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-6624","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/wp-json\/wp\/v2\/pages\/6624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/wp-json\/wp\/v2\/comments?post=6624"}],"version-history":[{"count":14,"href":"https:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/wp-json\/wp\/v2\/pages\/6624\/revisions"}],"predecessor-version":[{"id":7519,"href":"https:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/wp-json\/wp\/v2\/pages\/6624\/revisions\/7519"}],"up":[{"embeddable":true,"href":"https:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/wp-json\/wp\/v2\/pages\/494"}],"wp:attachment":[{"href":"https:\/\/informacionoficial.mendoza.gob.ar\/energiayambiente\/wp-json\/wp\/v2\/media?parent=6624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}